{"id":3280,"date":"2026-03-16T14:30:10","date_gmt":"2026-03-16T18:30:10","guid":{"rendered":"https:\/\/www.aclu-pr.org\/?post_type=press_release&#038;p=3280"},"modified":"2026-03-16T14:30:10","modified_gmt":"2026-03-16T18:30:10","slug":"expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico","status":"publish","type":"press_release","link":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/","title":{"rendered":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d"},"author":12,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"class_list":["post-3280","press_release","type-press_release","status-publish","hentry"],"acf":{"subheading":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d","date_and_time":"2025-06-19 09:00:00","featured_image":null,"components":[{"acf_fc_layout":"text","text":{"text":"Expresiones autorizadas de la licenciada Lolimar Escudero Rodr\u00edguez, abogada de Pol\u00edtica y Legislaci\u00f3n de la ACLU de Puerto Rico, sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d, entre otros fines:\r\n\r\n\u201cLa disposici\u00f3n contenida en el Proyecto de la C\u00e1mara 406 que faculta al Gobernador a confirmar previamente los nombramientos de oficiales con rango de Inspector, Comandante, Teniente Coronel y Coronel en la Polic\u00eda de Puerto Rico representa una alteraci\u00f3n en la distribuci\u00f3n de poder y es contraria a la Reforma Policial. Permitir que el Primer Ejecutivo influya directamente en la l\u00ednea de mando de la Polic\u00eda, una instituci\u00f3n con poder coercitivo sobre la ciudadan\u00eda, abre la puerta al uso indebido del poder policiaco. Delegar al Gobernador un rol adicional en la confirmaci\u00f3n de mandos de la Polic\u00eda erosiona la meritocracia y violenta la Reforma Policial a la que nuestra Polic\u00eda est\u00e1 sujeta por decreto judicial final. Adem\u00e1s, promueve un mandato susceptible a actos de corrupci\u00f3n, la politizaci\u00f3n de la Polic\u00eda y al abuso de poder\u201d."}}],"use_default_media_contact":true,"name":"","email":"","phone":"","address":{"address_1":"","address_2":"","city":"","state":"","zip_code":"","country":"United States"},"pgp_public_key":"","spokesperson":null,"related_content":[3272],"issues":[],"toggle-pdf":true,"documents":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d - ACLU of Puerto Rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d - ACLU of Puerto Rico\" \/>\n<meta property=\"og:description\" content=\"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/\" \/>\n<meta property=\"og:site_name\" content=\"ACLU of Puerto Rico\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aclu-pr.org\/app\/themes\/aclu-parent\/img\/default_fb_share.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/\",\"url\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/\",\"name\":\"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d - ACLU of Puerto Rico\",\"isPartOf\":{\"@id\":\"https:\/\/www.aclu-pr.org\/#website\"},\"datePublished\":\"2026-03-16T18:30:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Press Releases\",\"item\":\"https:\/\/www.aclu-pr.org\/press-releases\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aclu-pr.org\/#website\",\"url\":\"https:\/\/www.aclu-pr.org\/\",\"name\":\"ACLU of Puerto Rico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aclu-pr.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d - ACLU of Puerto Rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/","og_locale":"es_ES","og_type":"article","og_title":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d - ACLU of Puerto Rico","og_description":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d","og_url":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/","og_site_name":"ACLU of Puerto Rico","og_image":[{"url":"https:\/\/www.aclu-pr.org\/app\/themes\/aclu-parent\/img\/default_fb_share.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/","url":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/","name":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d - ACLU of Puerto Rico","isPartOf":{"@id":"https:\/\/www.aclu-pr.org\/#website"},"datePublished":"2026-03-16T18:30:10+00:00","breadcrumb":{"@id":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-de-la-camara-406-que-persigue-crear-la-ley-de-la-policia-de-puerto-rico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Press Releases","item":"https:\/\/www.aclu-pr.org\/press-releases\/"},{"@type":"ListItem","position":2,"name":"Expresiones autorizadas sobre el Proyecto de la C\u00e1mara 406, que persigue crear la \u201cLey de la Polic\u00eda de Puerto Rico\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aclu-pr.org\/#website","url":"https:\/\/www.aclu-pr.org\/","name":"ACLU of Puerto Rico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aclu-pr.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"ACLU of Puerto Rico","distributor_original_site_url":"https:\/\/www.aclu-pr.org\/es\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/types\/press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":1,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3280\/revisions"}],"predecessor-version":[{"id":3281,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3280\/revisions\/3281"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/legislation\/3272"}],"wp:attachment":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/media?parent=3280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}