{"id":3024,"date":"2026-02-25T15:56:26","date_gmt":"2026-02-25T19:56:26","guid":{"rendered":"https:\/\/www.aclu-pr.org\/?post_type=press_release&#038;p=3024"},"modified":"2026-03-02T09:51:53","modified_gmt":"2026-03-02T13:51:53","slug":"expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico","status":"publish","type":"press_release","link":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/","title":{"rendered":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico"},"author":12,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"class_list":["post-3024","press_release","type-press_release","status-publish","hentry"],"acf":{"subheading":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico","date_and_time":"2026-01-15 09:00:00","featured_image":null,"components":[{"acf_fc_layout":"text","text":{"text":"Expresiones autorizadas de la licenciada Annette Mart\u00ednez Orabona, directora ejecutiva de la ACLU de Puerto Rico, sobre el Proyecto del Senado 923 que pretende enmendar el art\u00edculo 92 en el C\u00f3digo Penal de Puerto Rico, que define \"asesinato\", para redefinir \"ser humano\" como el \"concebido en cualquier etapa de gestaci\u00f3n\":\r\n\r\n\"El tr\u00e1mite expedito e inadecuado que recibi\u00f3 el Proyecto del Senado 923 en el Senado, al inicio de la sesi\u00f3n legislativa de 2026, se suma a la larga lista de medidas aprobadas en el 2025 sin la discusi\u00f3n y an\u00e1lisis p\u00fablico correspondiente, pese a su impacto o posible impacto sobre derechos civiles y constitucionales. Ante tal acci\u00f3n, nuestro llamado se dirige ahora a los legisladores de la C\u00e1mara de Representantes, para que garantice un proceso transparente y participativo, mediante vistas p\u00fablicas en las que se escuche y atienda a todas las partes potencialmente afectadas por este proyecto que, de convertirse en ley, persigue sin duda la prohibici\u00f3n y criminalizaci\u00f3n del aborto en Puerto Rico\"."}}],"use_default_media_contact":true,"name":"","email":"","phone":"","address":{"address_1":"","address_2":"","city":"","state":"","zip_code":"","country":"United States"},"pgp_public_key":"","spokesperson":null,"related_content":[3225,3233],"issues":[],"toggle-pdf":true,"documents":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico - ACLU of Puerto Rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico - ACLU of Puerto Rico\" \/>\n<meta property=\"og:description\" content=\"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/\" \/>\n<meta property=\"og:site_name\" content=\"ACLU of Puerto Rico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T13:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aclu-pr.org\/app\/themes\/aclu-parent\/img\/default_fb_share.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/\",\"url\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/\",\"name\":\"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico - ACLU of Puerto Rico\",\"isPartOf\":{\"@id\":\"https:\/\/www.aclu-pr.org\/#website\"},\"datePublished\":\"2026-02-25T19:56:26+00:00\",\"dateModified\":\"2026-03-02T13:51:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Press Releases\",\"item\":\"https:\/\/www.aclu-pr.org\/press-releases\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aclu-pr.org\/#website\",\"url\":\"https:\/\/www.aclu-pr.org\/\",\"name\":\"ACLU of Puerto Rico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aclu-pr.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico - ACLU of Puerto Rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/","og_locale":"es_ES","og_type":"article","og_title":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico - ACLU of Puerto Rico","og_description":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico","og_url":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/","og_site_name":"ACLU of Puerto Rico","article_modified_time":"2026-03-02T13:51:53+00:00","og_image":[{"url":"https:\/\/www.aclu-pr.org\/app\/themes\/aclu-parent\/img\/default_fb_share.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/","url":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/","name":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico - ACLU of Puerto Rico","isPartOf":{"@id":"https:\/\/www.aclu-pr.org\/#website"},"datePublished":"2026-02-25T19:56:26+00:00","dateModified":"2026-03-02T13:51:53+00:00","breadcrumb":{"@id":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aclu-pr.org\/es\/press-releases\/expresiones-autorizadas-sobre-el-proyecto-del-senado-923-y-el-tramite-legislativo-para-enmendar-el-articulo-92-del-codigo-penal-de-puerto-rico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Press Releases","item":"https:\/\/www.aclu-pr.org\/press-releases\/"},{"@type":"ListItem","position":2,"name":"Expresiones autorizadas sobre el Proyecto del Senado 923 y el tr\u00e1mite legislativo para enmendar el Art\u00edculo 92 del C\u00f3digo Penal de Puerto Rico"}]},{"@type":"WebSite","@id":"https:\/\/www.aclu-pr.org\/#website","url":"https:\/\/www.aclu-pr.org\/","name":"ACLU of Puerto Rico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aclu-pr.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"ACLU of Puerto Rico","distributor_original_site_url":"https:\/\/www.aclu-pr.org\/es\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/types\/press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":2,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3024\/revisions"}],"predecessor-version":[{"id":3134,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3024\/revisions\/3134"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3233"},{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3225"}],"wp:attachment":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/media?parent=3024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}