{"id":3293,"date":"2026-03-17T10:35:51","date_gmt":"2026-03-17T14:35:51","guid":{"rendered":"https:\/\/www.aclu-pr.org\/?post_type=case&#038;p=3293"},"modified":"2026-03-17T13:29:32","modified_gmt":"2026-03-17T17:29:32","slug":"albeto-pierre-v-rebecca-gonzalez-et-al","status":"publish","type":"case","link":"https:\/\/www.aclu-pr.org\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/","title":{"rendered":"Albeto Pierre v. Rebecca Gonz\u00e1lez et al."},"author":12,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"case_status":[],"court":[],"class_list":["post-3293","case","type-case","status-publish","hentry"],"acf":{"case_number":"25-cv-01696 (cvr)","featured_image":null,"date_updated":"20260317","date_filed":"20251229","call_to_action":null,"attorney":"Ferm\u00edn Arraiza Navas & Yarima Gonz\u00e1lez Crespo","judge":"","pro_bono_firm":"","partner_organizations":"Cl\u00ednica de Inmigraci\u00f3n de la Escuela de Derecho de la Universidad de Puerto Rico & Cl\u00ednica de Asistencia Legal de la Facultad de Derecho de la Universidad Interamericana de Puerto Rico","summary":"La Uni\u00f3n Americana de Libertades Civiles (ACLU, en ingl\u00e9s) de Puerto Rico present\u00f3 una petici\u00f3n de <i>habeas corpus<\/i> de emergencia ante el Tribunal de Distrito de Estados Unidos para el Distrito de Puerto Rico, en representaci\u00f3n de Albeto Pierre, un inmigrante haitiano detenido por agentes federales la v\u00edspera de Navidad en Barrio Obrero en Santurce, mientras acompa\u00f1aba a su pareja a una cita prenatal.\r\n\r\nLa acci\u00f3n legal impugn\u00f3 la detenci\u00f3n arbitraria y carente de base legal, y solicita al tribunal su liberaci\u00f3n inmediata, as\u00ed como una orden para impedir su traslado inminente fuera de la jurisdicci\u00f3n de Puerto Rico.","components":null,"legal_documents":[{"court":120,"documents":[{"document_options":"document","document":3298,"title":"Expedited Appeal at Docket 1st Cir_","subtitle":"","date_filed":"20260206","drupal_node_id":"","slug":"","child_documents":null}]},{"court":131,"documents":[{"document_options":"document","document":3302,"title":"Order U.S. District Court - Middle District of Florida","subtitle":"","date_filed":"20260205","drupal_node_id":"","slug":"","child_documents":null}]},{"court":117,"documents":[{"document_options":"document","document":3294,"title":"Second Amended Habeas Corpus","subtitle":"","date_filed":"20260116","drupal_node_id":"","slug":"","child_documents":null}]},{"court":117,"documents":[{"document_options":"document","document":3296,"title":"Amended Habeas Corpus ","subtitle":"","date_filed":"20260103","drupal_node_id":"","slug":"","child_documents":null}]},{"court":117,"documents":[{"document_options":"document","document":3304,"title":"TRO Petition ","subtitle":"","date_filed":"20251229","drupal_node_id":"","slug":"","child_documents":null}]},{"court":117,"documents":[{"document_options":"document","document":3300,"title":"Habeas Corpus ","subtitle":"","date_filed":"20251229","drupal_node_id":"","slug":"","child_documents":null}]}],"plaintiffs":null,"co-counsel":null,"issues":[2784],"related_content_publications":null,"press_releases_related_to_cases":[3044,3022,2982,3042,2975],"related_news":null,"related_content_cases":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Albeto Pierre v. Rebecca Gonz\u00e1lez et al. - ACLU of Puerto Rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Albeto Pierre v. Rebecca Gonz\u00e1lez et al. - ACLU of Puerto Rico\" \/>\n<meta property=\"og:description\" content=\"La Uni\u00f3n Americana de Libertades Civiles (ACLU, en ingl\u00e9s) de Puerto Rico present\u00f3 una petici\u00f3n de habeas corpus de emergencia ante el Tribunal de Distrito de Estados Unidos para el Distrito de Puerto Rico, en representaci\u00f3n de Albeto Pierre, un inmigrante haitiano detenido por agentes federales la v\u00edspera de Navidad en Barrio Obrero en Santurce,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aclu-pr.org\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/\" \/>\n<meta property=\"og:site_name\" content=\"ACLU of Puerto Rico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T17:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aclu-pr.org\/app\/themes\/aclu-parent\/img\/default_fb_share.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/\",\"url\":\"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/\",\"name\":\"Albeto Pierre v. Rebecca Gonz\u00e1lez et al. - ACLU of Puerto Rico\",\"isPartOf\":{\"@id\":\"https:\/\/www.aclu-pr.org\/#website\"},\"datePublished\":\"2026-03-17T14:35:51+00:00\",\"dateModified\":\"2026-03-17T17:29:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cases\",\"item\":\"https:\/\/www.aclu-pr.org\/cases\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Albeto Pierre v. Rebecca Gonz\u00e1lez et al.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aclu-pr.org\/#website\",\"url\":\"https:\/\/www.aclu-pr.org\/\",\"name\":\"ACLU of Puerto Rico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aclu-pr.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Albeto Pierre v. Rebecca Gonz\u00e1lez et al. - ACLU of Puerto Rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/","og_locale":"es_ES","og_type":"article","og_title":"Albeto Pierre v. Rebecca Gonz\u00e1lez et al. - ACLU of Puerto Rico","og_description":"La Uni\u00f3n Americana de Libertades Civiles (ACLU, en ingl\u00e9s) de Puerto Rico present\u00f3 una petici\u00f3n de habeas corpus de emergencia ante el Tribunal de Distrito de Estados Unidos para el Distrito de Puerto Rico, en representaci\u00f3n de Albeto Pierre, un inmigrante haitiano detenido por agentes federales la v\u00edspera de Navidad en Barrio Obrero en Santurce,...","og_url":"https:\/\/www.aclu-pr.org\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/","og_site_name":"ACLU of Puerto Rico","article_modified_time":"2026-03-17T17:29:32+00:00","og_image":[{"url":"https:\/\/www.aclu-pr.org\/app\/themes\/aclu-parent\/img\/default_fb_share.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/","url":"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/","name":"Albeto Pierre v. Rebecca Gonz\u00e1lez et al. - ACLU of Puerto Rico","isPartOf":{"@id":"https:\/\/www.aclu-pr.org\/#website"},"datePublished":"2026-03-17T14:35:51+00:00","dateModified":"2026-03-17T17:29:32+00:00","breadcrumb":{"@id":"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/live-awp-puerto-rico.pantheonsite.io\/es\/cases\/albeto-pierre-v-rebecca-gonzalez-et-al\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cases","item":"https:\/\/www.aclu-pr.org\/cases\/"},{"@type":"ListItem","position":2,"name":"Albeto Pierre v. Rebecca Gonz\u00e1lez et al."}]},{"@type":"WebSite","@id":"https:\/\/www.aclu-pr.org\/#website","url":"https:\/\/www.aclu-pr.org\/","name":"ACLU of Puerto Rico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aclu-pr.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"ACLU of Puerto Rico","distributor_original_site_url":"https:\/\/www.aclu-pr.org\/es\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/case\/3293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/types\/case"}],"author":[{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":2,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/case\/3293\/revisions"}],"predecessor-version":[{"id":3388,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/case\/3293\/revisions\/3388"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/2975"},{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3042"},{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/2982"},{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3022"},{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/press_release\/3044"},{"embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/issue\/2784"}],"wp:attachment":[{"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/media?parent=3293"}],"wp:term":[{"taxonomy":"case_status","embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/case_status?post=3293"},{"taxonomy":"court","embeddable":true,"href":"https:\/\/www.aclu-pr.org\/es\/wp-json\/wp\/v2\/court?post=3293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}